{"id":22,"count":3,"description":"Business! Het woord zegt het al en wij kunnen jou beloven dat deze categorie aan al jouw verwachtingen zal voldoen. En we hebben het dan niet over alleen over onderwerpen als Google Business of Facebook business. Nee, we hebben het echt over alles wat met dit onderwerp te maken heeft.\r\n\r\nBen je een ondernemer en ben je op zoek naar tips om te groeien? Of wil jij gewoon simpelweg weten wat belangrijk is om werknemers aan te nemen en ook nog zo lang mogelijk binnen het bedrijf te houden?\r\n\r\nHier zit jij goed, want wij hebben speciaal voor jou al deze onderwerpen uitgelicht en zo goed mogelijk voor jou beschreven.\r\n\r\nVerder is het ook gemakkelijk lezen en kun je hier eens doorheen scrollen voor inspiratie, tips en tricks. Lees onze blogs nu!","link":"https:\/\/themodernmagazines.com\/de\/category\/business\/","name":"Gesch\u00e4ftlich","slug":"business","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alles wat jij moet weten omtrent business | themodernmagazines.com<\/title>\n<meta name=\"description\" content=\"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themodernmagazines.com\/de\/category\/business\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alles wat jij moet weten omtrent business | themodernmagazines.com\" \/>\n<meta property=\"og:description\" content=\"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themodernmagazines.com\/de\/category\/business\/\" \/>\n<meta property=\"og:site_name\" content=\"The modern magazines\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/themodernmagazines.com\/category\/business\/\",\"url\":\"https:\/\/themodernmagazines.com\/category\/business\/\",\"name\":\"Alles wat jij moet weten omtrent business | themodernmagazines.com\",\"isPartOf\":{\"@id\":\"https:\/\/themodernmagazines.com\/#website\"},\"description\":\"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!\",\"breadcrumb\":{\"@id\":\"https:\/\/themodernmagazines.com\/category\/business\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/themodernmagazines.com\/category\/business\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/themodernmagazines.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/themodernmagazines.com\/#website\",\"url\":\"https:\/\/themodernmagazines.com\/\",\"name\":\"The modern magazines\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/themodernmagazines.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alles wat jij moet weten omtrent business | themodernmagazines.com","description":"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themodernmagazines.com\/de\/category\/business\/","og_locale":"de_DE","og_type":"article","og_title":"Alles wat jij moet weten omtrent business | themodernmagazines.com","og_description":"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!","og_url":"https:\/\/themodernmagazines.com\/de\/category\/business\/","og_site_name":"The modern magazines","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/themodernmagazines.com\/category\/business\/","url":"https:\/\/themodernmagazines.com\/category\/business\/","name":"Alles wat jij moet weten omtrent business | themodernmagazines.com","isPartOf":{"@id":"https:\/\/themodernmagazines.com\/#website"},"description":"Hier vind je alles wat je moet weten omtrent het onderwerp business. Van tools tot aan methodes. Lees de blogartikelen nu!","breadcrumb":{"@id":"https:\/\/themodernmagazines.com\/category\/business\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/themodernmagazines.com\/category\/business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themodernmagazines.com\/"},{"@type":"ListItem","position":2,"name":"Business"}]},{"@type":"WebSite","@id":"https:\/\/themodernmagazines.com\/#website","url":"https:\/\/themodernmagazines.com\/","name":"The modern magazines","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themodernmagazines.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/themodernmagazines.com\/de\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themodernmagazines.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/themodernmagazines.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/themodernmagazines.com\/de\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}